{"id":2324,"date":"2022-05-02T18:49:28","date_gmt":"2022-05-02T18:49:28","guid":{"rendered":"https:\/\/www.ardiseny.es\/wordpress\/?p=2324"},"modified":"2023-02-08T20:11:42","modified_gmt":"2023-02-08T20:11:42","slug":"la-red-social-es-inevitable-en-el-siglo-xxi","status":"publish","type":"post","link":"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/","title":{"rendered":"La red social: es inevitable en el siglo XXI?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_84 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice de contenidos:<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a572c117aea7\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a572c117aea7\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/#La_Falsa_creencia_de_que_debemos_estar_en_Internet\" >La Falsa creencia de que debemos estar en Internet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/#La_verdadera_razon_de_porque_debemos_estar_en_Internet\" >La verdadera raz\u00f3n de porqu\u00e9 debemos estar en Internet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/#La_dependencia_de_las_redes_sociales\" >La dependencia de las redes sociales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/#Riesgos\" >Riesgos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.ardiseny.es\/wordpress\/la-red-social-es-inevitable-en-el-siglo-xxi\/#Ventajas_e_Inconvenientes\" >Ventajas e Inconvenientes<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"La_Falsa_creencia_de_que_debemos_estar_en_Internet\"><\/span>La Falsa creencia de que debemos estar en Internet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>Hay muchas razones por las que se cre\u00e9 que si no tenemos redes sociales no existimos.<\/p>\n<p>Es cierto que las redes sociales ocupan un espacio importante en la sociedad que vivimos, pero debemos <strong>relativizar<\/strong> las cosas. Las<strong> redes sociales<\/strong> son un concepto del marketing y por ello nos hacen depender de ellas.<\/p>\n<p>Existimos como sociedad hace m\u00e1s de 2000 a\u00f1os, pero ha sido en los \u00faltimos 50 a\u00f1os cuando la tecnolog\u00eda digital ha revolucionado o cambiado el mundo que nos rodea.<\/p>\n<p>Nos han echo creer que debemos estar en Internet o sino no existimos.<br \/>\nDebemos comprender o analizar si una empresa debe estar en Internet y porque.<\/p>\n<p><strong>Nos podemos preguntar:<\/strong><\/p>\n<ul>\n<li>Una empresa \u00bfPuede vivir sin internet?<\/li>\n<li>\u00bfPuede una empresa sobrevivir sin telefon\u00eda movil?<\/li>\n<li>\u00bfPuede una empresa vivir sin redes sociales?<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"La_verdadera_razon_de_porque_debemos_estar_en_Internet\"><\/span><a href=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales.jpg\"><img decoding=\"async\" width=\"745\" height=\"483\" class=\"aligncenter size-full wp-image-2336\" src=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales.jpg\" alt=\"\" srcset=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales.jpg 745w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales-300x194.jpg 300w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales-696x451.jpg 696w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/estarenredessociales-648x420.jpg 648w\" sizes=\"(max-width: 745px) 100vw, 745px\" \/><\/a>La verdadera raz\u00f3n de porqu\u00e9 debemos estar en Internet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>Como empresa debemos entender o comprender que las redes sociales, Internet, m\u00f3vil email, etc es una parte fundamental del <strong>Marketing<\/strong> y en definitiva es la respuesta sencilla de porque debemos estar en cada una de ellas.<\/p>\n<p>Si la empresa no est\u00e1 en los medios sociales no puede conocer lo que sucede y por ello se convierte en una ignorante en lo referente a Internet. Habr\u00e1 muchas empresas que dir\u00e1n que ellas facturan y trabajan sin necesidad de Internet, la respuesta: El progreso no se detiene por nadie y si no nos subimos al tren este nos dejar\u00e1 abandonados hasta desaparecer. Hoy d\u00eda ya se est\u00e1 implantando las facturas electr\u00f3nicas, las criptomonedas, trabajos colaborativos con herramientas de terceros(que est\u00e1n en Internet) y que decir que sin un email, hoy d\u00eda, las empresas no pueden funcionar.<\/p>\n<p>Otra cuesti\u00f3n es como las nuevas tecnolog\u00edas vienen a solucionar problemas concretos.<\/p>\n<p>Por ejemplo: Una empresa ten\u00eda que poner fotos para que los usuarios vieran sus productos o compartir con terceros para su distribuci\u00f3n. Si unos conocimientos t\u00e9cnicos no se pod\u00eda compartir fotos con la mayor\u00eda de personas. <strong>Las redes sociales<\/strong> han solucionado esos problemas y adem\u00e1s a contribuido a mejorar la calidad y la transmisi\u00f3n de las fotograf\u00edas por Internet.<\/p>\n<p>Hoy d\u00eda podemos pasar por un email archivos de v\u00eddeo, fotos, pdf, etc con una facilidad asombrosa.<\/p>\n<p>Reiteramos que es indispensable que una empresa deba estar en INTERNET: Es inevitable.<\/p>\n<p>[sociallocker]<\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_dependencia_de_las_redes_sociales\"><\/span>La dependencia de las redes sociales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>Tambi\u00e9n el marketing o Internet tiene su lado oscuro.<\/p>\n<p>Los que trabajos en algo relacionado con Internet tenemos dificultades en aislarnos de la tecnolog\u00eda y ello nos ocasiona problemas de dependencia. Las redes sociales son un producto de Marketing y por ello se han dise\u00f1ado para crear dependencia.<\/p>\n<p>Debemos analizar individualmente los casos personales y trabajar seriamente nuestro grado de dependencia. Una vez analizado debemos ir haciendo ejercicios para dejar o m\u00e1s bien descansar de las nuevas tecnolog\u00edas. Al final son una dependencia como otro trabajo puede ocasionar, pero cuando el trabajo son redes sociales y nuestra vida cotidiana tambi\u00e9n, es dif\u00edcil desconectar y ello nos puede ocasionar problemas en nuestra salud.<\/p>\n<p>Hay diferentes tipos de dependencia:<\/p>\n<ul>\n<li><strong>Dependencia funcional:<\/strong> Internet y las redes sociales son muy \u00fatiles hoy d\u00eda. Podemos encontrar restaurantes, tiendas, productos, gps que nos lleva al s\u00edtio, etc.<\/li>\n<li><strong>Dependencia para relacionarse:<\/strong> Nos gusta saber lo que hacen nuestros amigos y por ello nos genera dependencia saber donde est\u00e1n, que hacen, con quien has salidos, etc. Tambien es una facilidad para poder hablar a distancia sin gastar dinero y por ello genera mucha dependencia.<\/li>\n<li><strong>Dependencia Psicol\u00f3gica:<\/strong> <strong>Nomofob\u00eda:<\/strong> El miedo a separarse del m\u00f3vil. Con ello lo decimos todo.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Riesgos\"><\/span><a href=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia.jpg\"><img decoding=\"async\" width=\"659\" height=\"483\" class=\"aligncenter size-full wp-image-2339\" src=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia.jpg\" alt=\"\" srcset=\"https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia.jpg 659w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia-300x220.jpg 300w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia-80x60.jpg 80w, https:\/\/www.ardiseny.es\/wordpress\/http:\/\/wp.ardiseny.es\/wp-content\/uploads\/2022\/05\/nomofobia-573x420.jpg 573w\" sizes=\"(max-width: 659px) 100vw, 659px\" \/><\/a>Riesgos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>Nuestros datos personales, fotos, comentarios, etc&#8230;<\/p>\n<p>Al final si queremos algo tenemos que sacrificar cosas. Poner nuestra vida en Internet tiene un precio. Antiguamente la reputaci\u00f3n alcanzaba a nuestro pueblo o ciudad. Si eras una persona muy importante o famosa pod\u00edas llegar m\u00e1s lejos incluso que te conocieran en el mundo entero. Ten\u00edas que tener cuidado de lo que hac\u00edas, pero si comet\u00edas alg\u00fan desliz no quedaba grabado.<\/p>\n<p>Hoy d\u00eda con las redes sociales cualquier persona tiene el riesgo de arruinar su e-reputaci\u00f3n.<\/p>\n<p><strong>RIESGOS:<\/strong><\/p>\n<ul>\n<li><strong>Gesti\u00f3n digital de los datos:<\/strong> A fin de cuentas lo que est\u00e1 luchando la uni\u00f3n Europea, la protecci\u00f3n de datos.<\/li>\n<li><strong>E-reputaci\u00f3n:<\/strong> La imagen que proyectamos hacia los dem\u00e1s<\/li>\n<li><strong>Usurpaci\u00f3n digital:<\/strong> Que nos roben nuestro perfil y hagan fechor\u00edas en \u00e9l con ello arruinan la E-reputaci\u00f3n y nos roban los datos.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Ventajas_e_Inconvenientes\"><\/span>Ventajas e Inconvenientes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>Despu\u00e9s de lo explicado podemos definir una tabla con ventajas e inconvenientes:<\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 234px;\">\n<tbody>\n<tr style=\"background-color: #4b77bd;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"color: #ffffff;\">Ventajas<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"color: #ffffff;\">Inconvenientes<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Bajo coste<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Confidencialidad limitada de las herramientas<\/span><\/td>\n<\/tr>\n<tr style=\"height: 52px;\">\n<td style=\"width: 50%; text-align: center; height: 52px;\"><span style=\"font-size: 10pt;\">Poder de comunicaci\u00f3n<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 52px;\"><span style=\"font-size: 10pt;\">Inevitabilidad de las acciones de comunicaci\u00f3n<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Conexi\u00f3n 24h 365 d\u00edas a\u00f1o<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Estr\u00e9s potencial<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Fusi\u00f3n entre tecnolog\u00edas<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Independencias de las herramientas<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Interacci\u00f3n elevada<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Subjetividad elevada<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Relaciones humanas adicionales<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Mayor complejidad de las relaciones humanas<\/span><\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Innovaci\u00f3n<\/span><\/td>\n<td style=\"width: 50%; text-align: center; height: 26px;\"><span style=\"font-size: 10pt;\">Obligaci\u00f3n a seguir el avance tecnol\u00f3gico<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><span style=\"font-size: 10pt;\">Automatizar procesos<\/span><\/td>\n<td style=\"width: 50%; text-align: center;\"><span style=\"font-size: 10pt;\">Industrializaci\u00f3n de las relaciones humanas<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/sociallocker]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Falsa creencia de que debemos estar en Internet Hay muchas razones por las que se cre\u00e9 que si no tenemos redes sociales no existimos. Es cierto que las redes sociales ocupan un espacio importante en la sociedad que vivimos, pero debemos relativizar las cosas. Las redes sociales son un concepto del marketing y por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,45,46,47],"tags":[],"class_list":["post-2324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-marketing","category-marketing-digital","category-redes-sociales"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts\/2324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/comments?post=2324"}],"version-history":[{"count":0,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts\/2324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/media\/2326"}],"wp:attachment":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/media?parent=2324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/categories?post=2324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/tags?post=2324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}