{"id":2518,"date":"2023-06-30T17:39:33","date_gmt":"2023-06-30T17:39:33","guid":{"rendered":"https:\/\/www.ardiseny.es\/wordpress\/?p=2518"},"modified":"2023-06-30T17:39:33","modified_gmt":"2023-06-30T17:39:33","slug":"derecho-prohibicion-para-realizar-llamadas-comerciales","status":"publish","type":"post","link":"https:\/\/www.ardiseny.es\/wordpress\/derecho-prohibicion-para-realizar-llamadas-comerciales\/","title":{"rendered":"DERECHO: PROHIBICI\u00d3N PARA REALIZAR LLAMADAS COMERCIALES"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_84 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice de contenidos:<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56d7ccf2f63\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56d7ccf2f63\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.ardiseny.es\/wordpress\/derecho-prohibicion-para-realizar-llamadas-comerciales\/#Solo_se_pueden_realizar_llamadas_comerciales_si_se_dan_las_siguientes_condiciones_cuando_van_dirigidas_a\" >Solo se pueden realizar llamadas comerciales si se dan las siguientes condiciones, cuando van dirigidas a:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.ardiseny.es\/wordpress\/derecho-prohibicion-para-realizar-llamadas-comerciales\/#Reclamaciones\" >Reclamaciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.ardiseny.es\/wordpress\/derecho-prohibicion-para-realizar-llamadas-comerciales\/#28_de_junio_de_2023\" >(28 de junio de 2023).<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.ardiseny.es\/wordpress\/derecho-prohibicion-para-realizar-llamadas-comerciales\/#Enlace_a_la_nota_de_prensa_de_la_AEPD\" >Enlace a la nota de prensa de la AEPD<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Solo_se_pueden_realizar_llamadas_comerciales_si_se_dan_las_siguientes_condiciones_cuando_van_dirigidas_a\"><\/span><strong>Solo se pueden realizar llamadas comerciales si se dan las siguientes condiciones, cuando van dirigidas a:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>1. Personas f\u00edsicas, <\/b>en el caso de llamadas comerciales a particulares:<\/p>\n<ul>\n<li><b>Con consentimiento<\/b> <b>previo<\/b>: se debe poder acreditar con evidencias (documento, grabaci\u00f3n, checkbox, etc.)<\/li>\n<li><b>Sin consentimiento<\/b>: solo en el caso de que se den conjuntamente estas tres condiciones:<b><\/b>\n<ul>\n<li>La persona a la que se llama sea ya cliente, es decir exista una relaci\u00f3n contractual previa<b><sup>(1)<\/sup>.<\/b><b><\/b><\/li>\n<li>Sus datos se hayan obtenido de manera l\u00edcita.<b><\/b><\/li>\n<li>La llamada se refiera a productos o servicios similares a los ya comprados o contratados por el cliente a la entidad que llama, no de otras entidades.<b><\/b><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><b>2. Personas jur\u00eddicas<\/b>, en el caso de llamadas comerciales a personas que presten servicios a entidades (empleados, directivos, asociados, etc.), a empresarios individuales o a profesionales liberales:<\/p>\n<ul>\n<li><b>Con consentimiento<\/b> <b>previo<\/b>: se debe poder acreditar con evidencias (documento, grabaci\u00f3n, checkbox, etc.)<b><\/b><\/li>\n<li><b>Sin consentimiento<\/b>: solo en el caso de que se den conjuntamente estas tres condiciones:<b><\/b>\n<ul>\n<li>Que el n\u00famero de tel\u00e9fono se haya obtenido de gu\u00edas de abonados o en otros instrumentos similares.<\/li>\n<li>Que la llamada se refiera a la oferta de productos y servicios relacionados con la actividad profesional o empresarial.<\/li>\n<li>Que no se trate de entablar relaci\u00f3n en cuanto a tales personas f\u00edsicas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><b>3. En cualquier caso:<\/b><\/p>\n<ul>\n<li>Al inicio de cada llamada se debe facilitar la informaci\u00f3n sobre este tratamiento, es decir la identidad de la entidad que llama, la finalidad comercial de la llamada, los derechos que asisten al interesado, entre ellos el de revocar el consentimiento u oponerse a las llamadas, etc.<\/li>\n<li>Todas las llamadas deber\u00e1n grabarse.<\/li>\n<li>Si los n\u00fameros de tel\u00e9fono se generan de manera aleatoria, siempre se precisar\u00e1 el consentimiento.<\/li>\n<li>Antes de empezar una campa\u00f1a de llamadas comerciales, se deben consultar las listas de exclusi\u00f3n publicitaria (Lista Robinson), y las personas que est\u00e9n inscritas en ellas solo llamarlas si han prestado su consentimiento.<\/li>\n<li>Cualquier manifestaci\u00f3n inequ\u00edvoca del usuario contraria a la recepci\u00f3n de dichas llamadas deber\u00e1 entenderse como revocaci\u00f3n del consentimiento o, en su caso, como ejercicio del derecho de oposici\u00f3n, debiendo atenderse inmediatamente.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Reclamaciones\"><\/span><b>Reclamaciones<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Las entidades que incumplan estas obligaciones se expondr\u00e1n a ser multadas con sanciones de hasta 100.000 euros, para las faltas leves, y de hasta los 20 millones de euros, en los casos de infracciones muy graves.<\/p>\n<p>El organismo encargado de vigilar que se cumpla esta obligaci\u00f3n ser\u00e1 la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Cuando detecten o reciban una reclamaci\u00f3n de llamada comercial sin que se den ninguna de las circunstancias expuestas en los puntos 1 o 2, proceder\u00e1n a dirigirse a la entidad infractora e iniciar un procedimiento sancionador.<\/p>\n<h2 class=\"text-align-justify\"><span class=\"ez-toc-section\" id=\"28_de_junio_de_2023\"><\/span><strong>(28 de junio de 2023)<\/strong>.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"text-align-justify\">El Bolet\u00edn Oficial del Estado ha publicado <a title=\"Abre en ventana nueva\" href=\"https:\/\/www.boe.es\/boe\/dias\/2023\/06\/28\/pdfs\/BOE-A-2023-15071.pdf\" target=\"_blank\" rel=\"nofollow noopener\">la Circular de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos<\/a> (AEPD) sobre el derecho de los usuarios a no recibir llamadas no solicitadas, fijando los criterios que aplicar\u00e1 la Agencia en relaci\u00f3n con el art\u00edculo 66.1.b) de la Ley 11\/2022 General de Telecomunicaciones.<\/p>\n<p class=\"text-align-justify\">Este art\u00edculo, aplicable desde <strong>el 29 de junio de este a\u00f1o<\/strong>, recoge el derecho de los usuarios a no recibir llamadas con fines de comunicaci\u00f3n comercial no solicitadas, <strong>salvo que exista consentimiento previo<\/strong> del propio usuario para recibir este tipo de comunicaciones o que estas puedan <strong>ampararse en otra base de legitimaci\u00f3n<\/strong> de las previstas en el Reglamento General de Protecci\u00f3n de Datos (RGPD). El art\u00edculo de la Ley no limita exclusivamente la realizaci\u00f3n de las llamadas con fines de comunicaci\u00f3n comercial al consentimiento e incluye la posibilidad de que estas puedan realizarse con otras bases jur\u00eddicas. Ante las dudas suscitadas en la interpretaci\u00f3n de este art\u00edculo, la Circular de la Agencia contribuye a <strong>clarificar el criterio, ofreciendo seguridad jur\u00eddica<\/strong> tanto a aquellos que realizan las llamadas comerciales como a los usuarios que las reciben.<br \/>\n<span><em><span style=\"font-size: small;\">(<strong>Extra\u00eddo\u00a0de:<\/strong><\/span><a style=\"font-size: 10pt;\" href=\"https:\/\/www.aepd.es\/es\/prensa-y-comunicacion\/notas-de-prensa\/la-aepd-publica-la-circular-sobre-el-derecho-de-los-usuarios\" target=\"_blank\" rel=\"noopener\"> https:\/\/www.aepd.es\/es\/prensa-y-comunicacion\/notas-de-prensa\/la-aepd-publica-la-circular-sobre-el-derecho-de-los-usuarios<\/a><span style=\"font-size: small;\">)<\/span><\/em><\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Enlace_a_la_nota_de_prensa_de_la_AEPD\"><\/span><b>Enlace a la nota de prensa de la AEPD<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/www.aepd.es\/es\/prensa-y-comunicacion\/notas-de-prensa\/la-aepd-publica-la-circular-sobre-el-derecho-de-los-usuarios\">https:\/\/www.aepd.es\/es\/prensa-y-comunicacion\/notas-de-prensa\/la-aepd-publica-la-circular-sobre-el-derecho-de-los-usuarios<\/a><\/p>\n<p><i><sup>(1) <\/sup><\/i><i>Si la relaci\u00f3n contractual ya no est\u00e1 en vigor y el destinatario de la llamada realizado ninguna otra solicitud o interacci\u00f3n con la empresa que llama durante el \u00faltimo a\u00f1o, no se podr\u00e1 llamar.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo se pueden realizar llamadas comerciales si se dan las siguientes condiciones, cuando van dirigidas a: 1. Personas f\u00edsicas, en el caso de llamadas comerciales a particulares: Con consentimiento previo: se debe poder acreditar con evidencias (documento, grabaci\u00f3n, checkbox, etc.) Sin consentimiento: solo en el caso de que se den conjuntamente estas tres condiciones: La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,6,12,38],"tags":[],"class_list":["post-2518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-blog","category-de-todo-un-poco","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts\/2518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/comments?post=2518"}],"version-history":[{"count":0,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/posts\/2518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/media\/2519"}],"wp:attachment":[{"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/media?parent=2518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/categories?post=2518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ardiseny.es\/wordpress\/wp-json\/wp\/v2\/tags?post=2518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}